{"id":1466,"date":"2020-01-19T15:50:48","date_gmt":"2020-01-19T12:50:48","guid":{"rendered":"http:\/\/zettdekor.com\/urun\/drop-orta-sehpa\/"},"modified":"2020-01-19T15:50:48","modified_gmt":"2020-01-19T12:50:48","slug":"drop-orta-sehpa","status":"publish","type":"product","link":"https:\/\/www.zettdekor.com\/uz\/product\/drop-orta-sehpa\/","title":{"rendered":"Drop Orta Sehpa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1465,"template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.zettdekor.com\/uz\/wp-json\/wp\/v2\/product\/1466"}],"collection":[{"href":"https:\/\/www.zettdekor.com\/uz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.zettdekor.com\/uz\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zettdekor.com\/uz\/wp-json\/wp\/v2\/media\/1465"}],"wp:attachment":[{"href":"https:\/\/www.zettdekor.com\/uz\/wp-json\/wp\/v2\/media?parent=1466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}